{"id":939,"date":"2026-04-12T15:43:44","date_gmt":"2026-04-12T15:43:44","guid":{"rendered":"https:\/\/silk-pajamas.com\/16-momme-crepe-silk-t-shirt-crew-neck-lilac-supplier\/"},"modified":"2026-04-17T02:10:39","modified_gmt":"2026-04-17T02:10:39","slug":"16-momme-crepe-silk-t-shirt-crew-neck-lilac-supplier","status":"publish","type":"product","link":"https:\/\/silk-pajamas.com\/es\/16-momme-crepe-silk-t-shirt-crew-neck-lilac-supplier\/","title":{"rendered":"16 Momme Camiseta de crep\u00e9 de seda Cuello redondo Proveedor Lila"},"content":{"rendered":"<p>Confeccionada en crep\u00e9 de seda 16 momme, esta camiseta de seda combina el detalle del cuello redondo con un brillo suave y un tacto transpirable. El acabado lila le confiere un aspecto refinado, mientras que las tallas XL, XXL, 3XL, 4XL ayudan a cubrir la demanda b\u00e1sica. Adecuada para viajes y armarios de verano. Lavar a mano en fr\u00edo o en ciclo delicado.<\/p>","protected":false},"excerpt":{"rendered":"<p>16 Camiseta Momme Crepe de seda en color Lila. Cuello redondo, tacto ligero y tallas XL, XXL, 3XL, 4XL. Dise\u00f1ada para viajes.<\/p>","protected":false},"featured_media":1268,"template":"","meta":{"_gspb_post_css":""},"product_brand":[],"product_cat":[28],"product_tag":[900,920,921],"class_list":["post-939","product","type-product","status-publish","has-post-thumbnail","product_cat-silk-t-shirts","product_tag-16-momme-silk-t-shirt-lilac","product_tag-crepe-silk-t-shirt-crew-neck","product_tag-factory-silk-t-shirt-for-travel-use","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/silk-pajamas.com\/es\/wp-json\/wp\/v2\/product\/939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silk-pajamas.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/silk-pajamas.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/silk-pajamas.com\/es\/wp-json\/wp\/v2\/media\/1268"}],"wp:attachment":[{"href":"https:\/\/silk-pajamas.com\/es\/wp-json\/wp\/v2\/media?parent=939"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/silk-pajamas.com\/es\/wp-json\/wp\/v2\/product_brand?post=939"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/silk-pajamas.com\/es\/wp-json\/wp\/v2\/product_cat?post=939"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/silk-pajamas.com\/es\/wp-json\/wp\/v2\/product_tag?post=939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}